{"id":19732,"date":"2023-11-28T11:09:55","date_gmt":"2023-11-28T10:09:55","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=19732"},"modified":"2023-11-28T18:00:33","modified_gmt":"2023-11-28T17:00:33","slug":"un-bel-contratto-anche-per-lo-stato","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/","title":{"rendered":"Un bel contratto anche per lo Stato!*"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">I bancari stanno per concludere il loro contratto. Si annuncia un aumento medio dei minimi tabellari di 435 euro lordi mensili. Indubbiamente un bel risultato che testimonia sia la forza dei sindacati dei lavoratori che lo stato di salute del complesso delle banche italiane.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il problema \u00e8&nbsp;quanti di quei 435 euro entreranno nelle tasche dei lavoratori e quanti invece finiranno in quelle dello Stato come contributi e imposte. Naturalmente contributi e imposte servono a pagare pensioni, servizi sociali, sanit\u00e0 e quant\u2019altro \u00e8 erogato ai cittadini italiani. Il problema \u00e8 che quanto trattenuto a dipendenti e pensionati \u00e8 molto, soprattutto se confrontato con quanto versato da altre tipologie di contribuenti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguiamo il futuro destino dei 435 euro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La retribuzione media lorda annua&nbsp;del settore si aggira tra i 40 e i 42.000 euro. Il lavoratore bancario medio, quindi, \u00e9&nbsp;tra i \u201cricchi\u201d e non ha diritto al taglio contributivo di 6 punti fino a 35.000 euro. Dai 435 euro si deve quindi detrarre il 9,19% di contribuzione esistente nel settore.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dato il reddito imponibile del lavoratore medio, l\u2019aliquota marginale Irpef nazionale \u00e8 quella del 35%, da applicare all\u2019aumento contrattuale al netto della contribuzione (395,02 \u20ac). Il netto percepito \u00e8 pari quindi a 256,8 \u20ac.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia la decurtazione non \u00e8 finita: ci sono le addizionali Irpef regionali e comunali. A questo proposito ci sono i lavoratori \u201csfortunati\u201d, che abitano nelle regioni con addizionali molto alte (Lazio, Piemonte, Campania) e quelli che abitano in regioni che applicano l\u2019aliquota pi\u00f9 bassa (Basilicata, Sardegna, Sicilia, Valle d\u2019Aosta e Veneto).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prendiamo ad esempio un lavoratore che abita nella prima citt\u00e0 italiana, Roma, che \u201csubisce\u201d per questo un\u2019addizionale regionale del 3,33% e una comunale dello 0,9%. Secondo esempio \u00e8 quello di un lavoratore di una delle regioni con addizionale pi\u00f9 bassa, che si vedr\u00e0 applicata un\u2019aliquota regionale dell\u20191,23% e una comunale dello 0,5%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al 35% di tassazione nazionale si deve quindi aggiungere un ulteriore prelievo variabile tra un minimo di 1,28% e un massimo di 4,23%. Il netto, conseguentemente, varier\u00e0 tra un massimo di 251,7 \u20ac e un minimo di 240,1 \u20ac.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In conclusione: lo Stato, tra contributi e fisco, dei 435 euro lordi conquistati dal CCNL dei bancari per il lavoratore \u201cmedio\u201d se ne prende tra il 42% e il 44%, in cifra assoluta tra 183,3 \u20ac e 194,9 \u20ac. Una cifra che fa una certa impressione.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ai lavoratori con qualifiche pi\u00f9 elevate e con retribuzioni pi\u00f9 alte della media va ovviamente peggio. A partire da poco pi\u00f9 di 55.000 euro lordi di retribuzione nel caso del settore bancario, ossia poco meno di 2.800 euro netti mensili, che diventano 2,700\/2.600 euro considerando le addizionali comunali e regionali, l\u2019aliquota marginale da applicare agli aumenti di reddito sale al 43%. Quindi l\u2019aumento del CCNL per questi lavoratori, una volta detratti i contributi, sar\u00e0 soggetto a un\u2019aliquota Irpef complessiva (nazionale e locale) tra il 44,28% e il 47,23%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In definitiva, un aumento lordo di 100 euro per questi lavoratori si traduce in un aumento netto compreso tra 51 e 48 euro secondo il luogo di residenza. La met\u00e0 dell\u2019aumento va allo Stato!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Va relativamente meglio alle qualifiche pi\u00f9 basse, con retribuzioni inferiori alla media del settore, che possono usufruire del taglio del cuneo contributivo e, a partire da gennaio, dell\u2019unificazione delle aliquote del primo e del secondo scaglione. I lavoratori con retribuzione lorda tra 29.000 e 35.000 euro con aliquota Irpef nazionale del 35% usufruiscono del taglio contributivo di 6 punti. I lavoratori con retribuzione lorda tra 26.001 e 29.000 euro usufruiscono del taglio contributivo di 6 punti e della riduzione dell\u2019aliquota Irpef dal 25% al 23%. I lavoratori con retribuzione lorda tra 15.001 e 25.000 usufruiscono del taglio contributivo di 7 punti e della riduzione dell\u2019aliquota Irpef dal 25% al 23%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E\u2019 bene specificare, per\u00f2, che anche per questi lavoratori i benefici sono minori di quelli che appaiono in prima battuta. Infatti vanno tenute in considerazione due conseguenze prodotte dal combinato disposto di taglio contributivo e aumento contrattuale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il taglio contributivo produce un incremento di imponibile che aumenta il livello di tassazione, riducendo l\u2019effetto positivo del taglio dei contributi. L\u2019aumento contrattuale, rafforzato dal taglio dei contributi, produce un aumento di imponibile. Gli effetti sono rilevanti perch\u00e9 nei primi tre scaglioni attuali (nei primi due a partire dal prossimo anno) le detrazioni per lavoro dipendente sono decrescenti all\u2019aumentare dell\u2019imponibile.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In sintesi: aumento contrattuale e decontribuzione, aumentando l\u2019imponibile, determinano una diminuzione della detrazione e quindi un aumento della pressione fiscale. Da considerare, inoltre, che il valore nominale delle detrazioni \u00e8 fermo dal 2022 e queste sono quindi diminuite sensibilmente in termini reali nell\u2019ultimo anno e mezzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Supponiamo, ad esempio, per una retribuzione di 23.000 euro lorde, un incremento contrattuale di 200 euro al mese. Dato il taglio del cuneo, gli oneri ammontano solo a 4,38 \u20ac (2,19%). L\u2019imponibile di 195,62 euro produce un\u2019imposta lorda di 44,99 euro; l\u2019aumento di retribuzione imponibile rispetto alla situazione precedente causa una diminuzione della detrazione di 17,91 euro, cosicch\u00e9 l\u2019aumento netto (che pure si realizza ed \u00e8 apprezzabile) si riduce a 132,72 euro, pari al 66% del risultato contrattuale. Considerando infine le addizionali, l\u2019aumento netto si riduce di una cifra ulteriore compresa tra 3 e 8 euro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie al taglio del cuneo e alla riduzione delle aliquote fiscali la situazione delle retribuzioni basse nel caso di aumenti retributivi (di natura contrattuale, di merito, per straordinari) gode certamente di una situazione favorevole, ma soffre comunque gli effetti di un sistema fiscale che colpisce in modo particolare il lavoro dipendente e, quindi, i risultati della contrattazione. E\u2019 una considerazione che non deve essere dimenticata e che viene spesso ignorata dai media, anche quelli specialistici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il calcolo esemplificativo operato prendendo come riferimento il settore bancario si pu\u00f2 ovviamente replicare in ogni settore contrattuale ricavandone i medesimi risultati.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I medi\/alti livelli sono taglieggiati da un sistema fiscale che riduce fortemente l\u2019entit\u00e0 netta degli aumenti retributivi costringendo sindacato, imprese e lavoratori a ricorrere a ogni strumento utile per sfuggire a questa eccessiva pressione fiscale: social benefit, welfare aziendale, premi di risultato.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle retribuzioni pi\u00f9 basse \u00e8 stato concesso il taglio dei contributi, che \u00e8 per\u00f2 depotenziato dal sistema delle detrazioni decrescenti nell\u2019Irpef, meccanismo attualmente reso pi\u00f9 pesante dall\u2019alto livello di inflazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situazione delineata, seppure sinteticamente, pone in primo piano la necessit\u00e0 di una profonda revisione della struttura dell\u2019imposta sul reddito delle persone fisiche e rende urgente la revisione del disordinato sistema delle addizionali regionali e comunali.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I bancari stanno per concludere il loro contratto. Si annuncia un aumento medio dei minimi tabellari di 435 euro lordi mensili. Indubbiamente un bel risultato che testimonia sia la forza dei sindacati dei lavoratori che lo stato di salute del complesso delle banche italiane.\u00a0<\/p>\n","protected":false},"author":6372,"featured_media":19734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-19732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un bel contratto anche per lo Stato!* - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un bel contratto anche per lo Stato!* - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"I bancari stanno per concludere il loro contratto. Si annuncia un aumento medio dei minimi tabellari di 435 euro lordi mensili. Indubbiamente un bel risultato che testimonia sia la forza dei sindacati dei lavoratori che lo stato di salute del complesso delle banche italiane.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T10:09:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T17:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurizio Benetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio Benetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/\"},\"author\":{\"name\":\"Maurizio Benetti\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/f57720244e8a792adac051909e05411f\"},\"headline\":\"Un bel contratto anche per lo Stato!*\",\"datePublished\":\"2023-11-28T10:09:55+00:00\",\"dateModified\":\"2023-11-28T17:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/\"},\"wordCount\":1037,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/banche-bancari-1170x550-1.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/\",\"name\":\"Un bel contratto anche per lo Stato!* - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/banche-bancari-1170x550-1.jpg\",\"datePublished\":\"2023-11-28T10:09:55+00:00\",\"dateModified\":\"2023-11-28T17:00:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/banche-bancari-1170x550-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/banche-bancari-1170x550-1.jpg\",\"width\":1170,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/un-bel-contratto-anche-per-lo-stato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un bel contratto anche per lo Stato!*\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/f57720244e8a792adac051909e05411f\",\"name\":\"Maurizio Benetti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g\",\"caption\":\"Maurizio Benetti\"},\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/maurizio-benetti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un bel contratto anche per lo Stato!* - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/","og_locale":"it_IT","og_type":"article","og_title":"Un bel contratto anche per lo Stato!* - Nuovi Lavori","og_description":"I bancari stanno per concludere il loro contratto. Si annuncia un aumento medio dei minimi tabellari di 435 euro lordi mensili. Indubbiamente un bel risultato che testimonia sia la forza dei sindacati dei lavoratori che lo stato di salute del complesso delle banche italiane.\u00a0","og_url":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/","og_site_name":"Nuovi Lavori","article_published_time":"2023-11-28T10:09:55+00:00","article_modified_time":"2023-11-28T17:00:33+00:00","og_image":[{"width":1170,"height":550,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg","type":"image\/jpeg"}],"author":"Maurizio Benetti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maurizio Benetti","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/"},"author":{"name":"Maurizio Benetti","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/f57720244e8a792adac051909e05411f"},"headline":"Un bel contratto anche per lo Stato!*","datePublished":"2023-11-28T10:09:55+00:00","dateModified":"2023-11-28T17:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/"},"wordCount":1037,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/","url":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/","name":"Un bel contratto anche per lo Stato!* - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg","datePublished":"2023-11-28T10:09:55+00:00","dateModified":"2023-11-28T17:00:33+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/11\/banche-bancari-1170x550-1.jpg","width":1170,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/un-bel-contratto-anche-per-lo-stato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Un bel contratto anche per lo Stato!*"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/f57720244e8a792adac051909e05411f","name":"Maurizio Benetti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2e4c5be86702a87b452b6ffd2802e871b12c0b6040b6bae67c0e4dc73c998f0?s=96&d=mm&r=g","caption":"Maurizio Benetti"},"url":"https:\/\/nuovi-lavori.it\/index.php\/author\/maurizio-benetti\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6372"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=19732"}],"version-history":[{"count":1,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19732\/revisions"}],"predecessor-version":[{"id":19735,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19732\/revisions\/19735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/19734"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=19732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=19732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=19732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}