{"id":19781,"date":"2023-12-12T22:35:41","date_gmt":"2023-12-12T21:35:41","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=19781"},"modified":"2023-12-13T18:03:08","modified_gmt":"2023-12-13T17:03:08","slug":"i-benefici-del-lavorare-tutti-di-meno","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/","title":{"rendered":"I benefici del lavorare tutti di meno"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Prima Intesa Sanpaolo (28mila bancari), poi Luxottica (15mila dipendenti) hanno introdotto la settimana lavorativa di 4 giorni per 20 settimane all\u2019anno (5 giorni di permessi individuali dei dipendenti e 15 giorni pagati dall\u2019azienda). Anche Leonardo (51mila dipendenti, 31mila in Italia) e Lamborghini (2mila) sono interessate a passare da 35 ore a 32 (con settimane alternate di 4 e 5 giorni).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I bancari erano stati i primi a scendere da 37,5 ore a 37 settimanali dopo quattro decenni in cui la riduzione degli orari era sparita, complice la vulgata liberista del massimo profitto. Ora ci si \u00e8 accorti che i lavoratori sono sempre pi\u00f9 stanchi di chi fa lauti profitti e non paga in modo adeguato e, chi pu\u00f2, si licenzia. In Usa sono stati 40 milioni, in Italia circa 3 (di cui met\u00e0 giovani).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juliet Schor del Boston College pubblic\u00f2 negli anni \u201990<em> The Overworked American<\/em> che seguiva il nostro <em>Lavorare meno lavorare tutti<\/em> di Cacace, Frey e Morese del 1978, che proponeva di riprendere la riduzione di orario fermatasi negli anni \u201980, al punto che in Usa c\u2019erano 164 ore annue in pi\u00f9, come in molti paesi (tra cui l\u2019Italia). Chi aveva proseguito nella riduzione di orario, come 56 imprese inglesi, aveva mostrato che con meno ore potevano crescere sia i ricavi che il benessere dei dipendenti (ansia, stanchezza e sonno -40% e assenze -65%). Inoltre minor inquinamento da traffico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 1850 le ore di lavoro in America ed Europa erano 72 alla settimana (12 ore per 6 giorni) e proprio le innovazioni tecnologiche (macchina a vapore\u2026) avevano peggiorato le condizioni per pi\u00f9 di un secolo (dal 1750 al 1860). Ci sono voluti i contro poteri dei sindacati per invertire la rotta. Nel 1886 i lavoratori dell\u2019Haymarket di Chicago con uno sciopero ottennero la giornata di 8 ore di lavoro. Poi sar\u00e0 Ford a introdurre la settimana di 40 ore nel 1926 perch\u00e9 non poteva avere un turn over del 370% e cap\u00ec che i benefici dovevano andare anche ai lavoratori. In Italia si dovr\u00e0 aspettare 40 anni (1969-70) per vedere applicata la settimana di 40 ore e la grande conquista delle pensioni.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Chi \u00e8 andato pi\u00f9 avanti di tutti \u00e8 la Germania dove si lavora in media 1.400 ore all\u2019anno contro le 1.770 dell\u2019Italia e degli Usa, ma sono ormai 40 anni che l\u2019ideologia liberista ha fatto abbandonare questa evidenza e cio\u00e8 che ridurre l\u2019orario fa bene a tutti, al lavoro, al capitale e all\u2019economia reale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La storia riserva per\u00f2 sempre delle sorprese e come diceva J.F. Kennedy: \u00abSe gli uomini hanno la capacit\u00e0 di inventare nuove macchine che tolgono lavoro ad altri uomini, hanno anche la capacit\u00e0 di rimetterli al lavoro\u00bb, se ci sono per\u00f2 i contro poteri (sindacati, associazioni\u2026) che sono in grado di contrastare e negoziare la logica di chi vorrebbe usare l\u2019Intelligenza Artificiale per automatizzare e sorvegliare e non come utilit\u00e0 per arricchire le mansioni di chi lavora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>L\u2019accordo sindacale della settimana corta in Luxottica ha oscurato un aspetto che \u00e8 ancora pi\u00f9 importante: il part-time per chi va in pensione negli ultimi tre anni con paga piena con l\u2019inserimento di un giovane a tempo pieno. Questo tandem (pi\u00f9 che staffetta) favorisce il rilancio e la produttivit\u00e0 delle imprese perch\u00e9 conserva sia l\u2019expertise dell\u2019anziano sia le innovazioni che porta il giovane. Nel lavoro (e pi\u00f9 avanza l\u2019et\u00e0), si fanno spesso per met\u00e0 tempo cose importantissime e per met\u00e0 routine, per cui con un part-time si \u00e8 spesso in grado di dare all\u2019azienda il 90% della propria <em>expertise<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa politica evita i costosi pre-pensionamenti che sono ancora largamente usati. Il recente accordo tra Tim e sindacati Tlc prevede duemila uscite volontarie per chi \u00e8 a 4-7 anni dalla pensione. L\u2019accordo sfrutta un articolo della legge Fornero che consente di andare in pensione anticipata fino a 7 anni entro il 2026 seppure con onere a totale carico dell\u2019azienda. Si tratta di politiche antiquate e costose per le stesse aziende e uno spreco enorme di manodopera se si pensa all\u2019enorme bisogno di lavoratori per via dell\u2019inverno demografico (meno 8 milioni in et\u00e0 di lavoro entro il 2050).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I sindacati potrebbero rilanciare la buona pratica Luxottica come riforma del sistema pensionistico. Insieme a flussi migratori legali (programmati e organizzati che portino al lavoro), occorre favorire il tandem a favore sia dell\u2019occupazione di giovani e donne, sia dell\u2019invecchiamento attivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima Intesa Sanpaolo (28mila bancari), poi Luxottica (15mila dipendenti) hanno introdotto la settimana lavorativa di 4 giorni per 20 settimane all\u2019anno (5 giorni di permessi individuali dei dipendenti e 15 giorni pagati dall\u2019azienda). <\/p>\n","protected":false},"author":6455,"featured_media":19784,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-19781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I benefici del lavorare tutti di meno - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I benefici del lavorare tutti di meno - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"Prima Intesa Sanpaolo (28mila bancari), poi Luxottica (15mila dipendenti) hanno introdotto la settimana lavorativa di 4 giorni per 20 settimane all\u2019anno (5 giorni di permessi individuali dei dipendenti e 15 giorni pagati dall\u2019azienda).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-12T21:35:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-13T17:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Gandini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Gandini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/\"},\"author\":{\"name\":\"Andrea Gandini\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/74eb439af601c010b0141d798a984055\"},\"headline\":\"I benefici del lavorare tutti di meno\",\"datePublished\":\"2023-12-12T21:35:41+00:00\",\"dateModified\":\"2023-12-13T17:03:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lavorare-meno-lavorare-tutti-620x414-1.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/\",\"name\":\"I benefici del lavorare tutti di meno - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lavorare-meno-lavorare-tutti-620x414-1.jpg\",\"datePublished\":\"2023-12-12T21:35:41+00:00\",\"dateModified\":\"2023-12-13T17:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lavorare-meno-lavorare-tutti-620x414-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lavorare-meno-lavorare-tutti-620x414-1.jpg\",\"width\":620,\"height\":414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/i-benefici-del-lavorare-tutti-di-meno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I benefici del lavorare tutti di meno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/74eb439af601c010b0141d798a984055\",\"name\":\"Andrea Gandini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g\",\"caption\":\"Andrea Gandini\"},\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/andrea-gandini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I benefici del lavorare tutti di meno - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/","og_locale":"it_IT","og_type":"article","og_title":"I benefici del lavorare tutti di meno - Nuovi Lavori","og_description":"Prima Intesa Sanpaolo (28mila bancari), poi Luxottica (15mila dipendenti) hanno introdotto la settimana lavorativa di 4 giorni per 20 settimane all\u2019anno (5 giorni di permessi individuali dei dipendenti e 15 giorni pagati dall\u2019azienda).","og_url":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/","og_site_name":"Nuovi Lavori","article_published_time":"2023-12-12T21:35:41+00:00","article_modified_time":"2023-12-13T17:03:08+00:00","og_image":[{"width":620,"height":414,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg","type":"image\/jpeg"}],"author":"Andrea Gandini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Gandini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/"},"author":{"name":"Andrea Gandini","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/74eb439af601c010b0141d798a984055"},"headline":"I benefici del lavorare tutti di meno","datePublished":"2023-12-12T21:35:41+00:00","dateModified":"2023-12-13T17:03:08+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/"},"wordCount":708,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/","url":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/","name":"I benefici del lavorare tutti di meno - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg","datePublished":"2023-12-12T21:35:41+00:00","dateModified":"2023-12-13T17:03:08+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2023\/12\/lavorare-meno-lavorare-tutti-620x414-1.jpg","width":620,"height":414},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/i-benefici-del-lavorare-tutti-di-meno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"I benefici del lavorare tutti di meno"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/74eb439af601c010b0141d798a984055","name":"Andrea Gandini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8ff89918fcd76b9330bcdb93540bc7e2165f3f7045dfbc33101a57cb690e604?s=96&d=mm&r=g","caption":"Andrea Gandini"},"url":"https:\/\/nuovi-lavori.it\/index.php\/author\/andrea-gandini\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6455"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=19781"}],"version-history":[{"count":2,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19781\/revisions"}],"predecessor-version":[{"id":19785,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/19781\/revisions\/19785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/19784"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=19781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=19781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=19781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}