{"id":20280,"date":"2024-04-23T11:11:27","date_gmt":"2024-04-23T09:11:27","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=20280"},"modified":"2024-04-23T19:15:36","modified_gmt":"2024-04-23T17:15:36","slug":"chimico","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/","title":{"rendered":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Anton Korinek e Donghyun Sun, ricercatori dell\u2019Universit\u00e0 della Virginia, hanno condotto uno studio sulle implicazioni economiche della transizione verso l\u2019<strong>Artificial General Intelligence <\/strong>(<strong>AGI<\/strong>), definita come <strong>l\u2019abilit\u00e0 dell\u2019Intelligenza Artificiale (IA) di svolgere tutte le attivit\u00e0 umane<\/strong>. Il documento, pubblicato dal <strong>National Bureau of Economic Research<\/strong>, costituisce un importante strumento per indagare la relazione tra il progresso tecnologico \u2013 inteso come automazione dei mestieri \u2013 e l\u2019andamento delle retribuzioni. Gli Autori, infatti, cercano di evidenziare attraverso analisi economiche le implicazioni sui salari e sull\u2019occupazione derivanti dalla transizione verso la piena automazione.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Simulando quattro diversi scenari (business-as-usual scenario, baseline AGI scenario, aggressive AGI scenario e mixed scenario), vengono presentati i possibili effetti di diversi livelli di automazione<\/strong>. L\u2019obiettivo \u00e8 quello di comprendere quale equilibrio sia preferibile e verso quale direzione tendere. Il progresso tecnologico non agisce in modo neutro sulla societ\u00e0 e sull\u2019economia; pertanto, \u00e8 necessario possedere dei validi strumenti per capire come perseguire un efficace bilanciamento fra i vari interessi in gioco.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I mestieri e le professioni sono soggetti a continui cambiamenti e per comprendere meglio la transizione verso l\u2019AGI, <strong>gli Autori classificano il lavoro umano in base alla complessit\u00e0 dei compiti<\/strong>. Ciascun lavoro pu\u00f2 essere suddiviso in diversi micro-compiti (o <strong>compiti atomistici<\/strong>). Ad esempio, il lavoro dell\u2019economista si compone di: studio dei dati economici e statistici; ricerca su questioni economiche e successiva diffusione della ricerca; compilazione, analisi e report di dati relativi ai fenomeni economici e alle tendenze del mercato; supervisione di progetti di ricerca altrui; insegnamento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciascun compito pu\u00f2 essere eseguito da una macchina con maggiore o minore difficolt\u00e0. <strong>La complessit\u00e0 dei compiti umani, infatti, si traduce in complessit\u00e0 computazionale. <\/strong>Un compito facilmente eseguibile da un essere umano pu\u00f2 essere difficile da riprodurre per un computer e viceversa. Attraverso questo <strong>\u00abcompute-centric framework\u00bb <\/strong>gli Autori individuano una \u201c<strong>soglia di complessit\u00e0<\/strong>\u201d che permette di determinare quali compiti possono essere automatizzati in un dato momento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dalla valutazione delle complessit\u00e0 delle professioni, gli Autori delineano <strong>due scenari opposti: nel primo la complessit\u00e0 delle competenze umane \u00e8 illimitata e la piena automazione non \u00e8 tecnicamente possibile, nel secondo i compiti umani sono limitati e consentono il raggiungimento dell\u2019AGI.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie a dimostrazioni a carattere economico, gli Autori spiegano l\u2019andamento dei salari in rapporto a diversi fattori: all\u2019automazione, all\u2019accumulazione di capitale, alla produttivit\u00e0 e alla scarsit\u00e0 di manodopera. Con il modello del <strong>Factor Price Frontier (FPF), <\/strong>emerge che gli effetti dell\u2019automazione presentano una forma a U rovesciata: <strong>per bassi livelli di automazione, i salari aumentano con l\u2019aumentare della produttivit\u00e0; al contrario, sopra una certa soglia di automazione, i salari diminuiscono<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per presentare la loro tesi, gli Autori si avvalgono di quattro scenari. Nello scenario <strong>business-as- usual <\/strong>non \u00e8 possibile raggiungere la piena automazione e una frazione costante di compiti \u00e8 automatizzata periodicamente con una crescita esponenziale dell\u2019indice di automazione. In questa circostanza, si prevede che i salari e la produzione continuino a crescere all\u2019infinito. In altri due scenari, invece, l\u2019AGI \u00e8 raggiunta ma in tempi diversi: nel <strong>baseline AGI scenario <\/strong>la piena automazione viene fissata in 20 anni, nell\u2019<strong>aggressive AGI scenario <\/strong>si prevede che ci\u00f2 avvenga in 5 anni. In queste due ipotesi i salari crollano con l\u2019avvicinarsi del momento della piena automazione. Lo <strong>scenario <\/strong>pi\u00f9 interessante, per\u00f2, \u00e8 quello <strong>misto<\/strong>: qui gli Autori considerano che vi sia un\u2019ampia copertura dell\u2019automazione nel breve termine (ad esempio perch\u00e9 viene reso computabile il lavoro cognitivo), ma prevedono che rimanga una lunga coda di compiti non automatizzabili. Gli esiti sui salari, in questo caso, sarebbero inizialmente allarmanti per poi ritornare ad aumentare con la crescita della produzione.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queste simulazioni nel breve e nel lungo periodo sono fondamentali <strong>per studiare come i governi potrebbero agire per massimizzare i salari perseguendo il tasso ottimale di automazione costante nel tempo<\/strong>. Gli Autori dimostrano come, rallentando l\u2019automazione, si possano aumentare i salari anche negli scenari in cui l\u2019AGI \u00e8 completata. Se da un lato questo rallentamento comporta un costo \u2013 non solo in termini di limitazione del progresso tecnologico ma anche di riduzione della crescita della produzione \u2013; dall\u2019altro permette una crescita perpetua dei salari. <strong>Secondo gli Autori, dunque, se l\u2019automazione \u00e8 lenta, allora ci sar\u00e0 sempre del lavoro da compiere per gli uomini. Se invece si raggiunge la piena automazione, i salari crolleranno. Questa tendenza, per\u00f2, si pu\u00f2 invertire.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In conclusione, <strong>il progresso tecnologico ha degli effetti sul mercato del lavoro e sull\u2019economia che non possono essere ignorati. <\/strong>In un contesto in cui \u00e8 sempre pi\u00f9 facile automatizzare i compiti umani, tanto quelli manuali quanto quelli intellettuali e creativi, \u00e8 cruciale comprendere le implicazioni della sostituzione dei lavoratori da parte di sistemi autonomi.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se il <em>paper <\/em>invita a una presa di responsabilit\u00e0 <em>in primis <\/em>da parte di politici e legislatori, dall\u2019evoluzione delle competenze e dei salari \u00e8 coinvolta la cittadinanza tutta. Il tema dell\u2019intelligenza artificiale \u00e8 oggetto di numerose norme, da ultimo <em>l\u2019AI Act <\/em>approvato dal Parlamento Europeo lo scorso 13 marzo. Questo testo ha gi\u00e0 sollevato delle critiche per l\u2019eccessiva limitazione al progresso tecnologico e la sua obsolescenza nel momento in cui gli si dovr\u00e0 dare applicazione. Risulta quindi evidente che la regolamentazione dell\u2019IA \u2013 e a maggior ragione dell\u2019AGI \u2013 non solleva solo un tema di responsabilit\u00e0 politica ma anche di accettabilit\u00e0 sociale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Italia, <strong>gli attori che sono direttamente coinvolti nella tutela dei salari sono le parti sociali con la contrattazione collettiva<\/strong>. Infatti, lo studio di Korinerk e Sun pu\u00f2 essere un valido strumento per <strong>interrogarsi su qual \u00e8 il bilanciamento migliore per garantire le esigenze di tutte le parti coinvolte dal progresso tecnologico e dal nuovo panorama che con esso si potr\u00e0 presentare<\/strong>. <strong>In ultima analisi, l\u2019invito \u00e8 quello di continuare a riflettere sui costi \u2013 economici e sociali \u2013 e sui benefici che il perseguimento della piena automazione pu\u00f2 comportare. <\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Yunior Fellow, Bollettino ADAPT, 02\/04\/2024, n.13<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anton Korinek e Donghyun Sun, ricercatori dell\u2019Universit\u00e0 della Virginia, hanno condotto uno studio sulle implicazioni economiche della transizione verso l\u2019Artificial General Intelligence (AGI), definita come l\u2019abilit\u00e0 dell\u2019Intelligenza Artificiale (IA) di svolgere tutte le attivit\u00e0 umane.<\/p>\n","protected":false},"author":6485,"featured_media":20323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-20280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/chimico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"Anton Korinek e Donghyun Sun, ricercatori dell\u2019Universit\u00e0 della Virginia, hanno condotto uno studio sulle implicazioni economiche della transizione verso l\u2019Artificial General Intelligence (AGI), definita come l\u2019abilit\u00e0 dell\u2019Intelligenza Artificiale (IA) di svolgere tutte le attivit\u00e0 umane.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/chimico\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T09:11:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T17:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1047\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federica Chirico*\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica Chirico*\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/\"},\"author\":{\"name\":\"Federica Chirico*\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/8b93e274753badc28543fe38ca848cfb\"},\"headline\":\"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari\",\"datePublished\":\"2024-04-23T09:11:27+00:00\",\"dateModified\":\"2024-04-23T17:15:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/\"},\"wordCount\":985,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Bizzotto-01.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/\",\"name\":\"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Bizzotto-01.jpg\",\"datePublished\":\"2024-04-23T09:11:27+00:00\",\"dateModified\":\"2024-04-23T17:15:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Bizzotto-01.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Bizzotto-01.jpg\",\"width\":1500,\"height\":1047},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/chimico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/8b93e274753badc28543fe38ca848cfb\",\"name\":\"Federica Chirico*\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g\",\"caption\":\"Federica Chirico*\"},\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/federica-chirico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/","og_locale":"it_IT","og_type":"article","og_title":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori","og_description":"Anton Korinek e Donghyun Sun, ricercatori dell\u2019Universit\u00e0 della Virginia, hanno condotto uno studio sulle implicazioni economiche della transizione verso l\u2019Artificial General Intelligence (AGI), definita come l\u2019abilit\u00e0 dell\u2019Intelligenza Artificiale (IA) di svolgere tutte le attivit\u00e0 umane.","og_url":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/","og_site_name":"Nuovi Lavori","article_published_time":"2024-04-23T09:11:27+00:00","article_modified_time":"2024-04-23T17:15:36+00:00","og_image":[{"width":1500,"height":1047,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg","type":"image\/jpeg"}],"author":"Federica Chirico*","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Federica Chirico*","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/"},"author":{"name":"Federica Chirico*","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/8b93e274753badc28543fe38ca848cfb"},"headline":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari","datePublished":"2024-04-23T09:11:27+00:00","dateModified":"2024-04-23T17:15:36+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/"},"wordCount":985,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/","url":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/","name":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg","datePublished":"2024-04-23T09:11:27+00:00","dateModified":"2024-04-23T17:15:36+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/chimico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2024\/04\/Bizzotto-01.jpg","width":1500,"height":1047},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/chimico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Gli effetti dell\u2019IA generale sugli stipendi: quattro scenari"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/8b93e274753badc28543fe38ca848cfb","name":"Federica Chirico*","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73dbcbd356b9900d238c1407405012eafbd5df217874f598040d907584a0b3d3?s=96&d=mm&r=g","caption":"Federica Chirico*"},"url":"https:\/\/nuovi-lavori.it\/index.php\/author\/federica-chirico\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/20280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6485"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=20280"}],"version-history":[{"count":3,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/20280\/revisions"}],"predecessor-version":[{"id":20337,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/20280\/revisions\/20337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/20323"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=20280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=20280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=20280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}