{"id":21710,"date":"2025-03-24T10:35:31","date_gmt":"2025-03-24T09:35:31","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=21710"},"modified":"2025-03-25T18:05:46","modified_gmt":"2025-03-25T17:05:46","slug":"what-where-who-when-why-al-tempo-della-ia","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/","title":{"rendered":"What? Where? Who? When? Why? al tempo della IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mercoled\u00ec 19 marzo, San Giuseppe, mentre il governo faceva approvare al senato una legge denominata pomposamente regolamento per l\u2019intelligenza artificiale, che poco incide sui casi concreti quale quello che stiamo esaminando e mentre l\u2019Ordine dei giornalisti era troppo affaccendato con le operazioni di voto per il rinnovo dei vertici, Il Foglio, quotidiano fondato da Giuliano Ferrara, usciva con un supplemento completamento redatto da un sistema artificiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non si \u00e8 trattato di un approfondimento, o di un allegato su un tema collaterale: era un vero duplicato del giornale che riproduceva completamente l\u2019impaginazione e la struttura editoriale con altri contenuti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il messaggio era chiaro: siamo alla vigilia dio una radicale sostituzione, in cui, se vogliamo, possiamo sostituire l\u2019intera redazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il direttore responsabile, e vedremo poi quanto responsabile, Claudio Cerasa, nella presentazione dell\u2019iniziativa, scrive che i giornalisti hanno formulato le domande e controllato le risposte dell\u2019intelligenza artificiale. pensando cos\u00ec di rassicurare, sia i suoi redattore che i lettori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il giorno dopo il fondatore della testata, Giuliano Ferrara in persona, ha definito l\u2019esibizione tecnologica \u201cuna vera opera d\u2019arte\u201d, mostrando stupore e meraviglia per il grado di assoluta sofisticatezza del risultato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In realt\u00e0 si \u00e8 trattato di cosa nota.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da tempo, era gi\u00e0 stato anticipato dai principali quotidiani internazionali: un uso diretto di dispositivi di intelligenza artificiale per elaborare, sulla base di domande mirate della redazione, articoli e schede editoriali. La novit\u00e0 del Foglio \u00e8 quella di concentrare in una sola giornata le domanda da fare ai meccanismi generativi, in base ai temi di maggiore attualit\u00e0, e pubblicare tutte insieme le risposte, riproducendo appunto l\u2019intero giornale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il risultato, come ormai ci si aspetta, se ben preparato, \u00e8 davvero di alto profilo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sia per la forma, che per il contenuto, il lavoro dell\u2019intelligenza artificiale appare estremamente affine al lavoro tradizionale della redazione: stile, ritmo, taglio editoriale e approccio critico sono sovrapponibili alla copia originale del quotidiano realizzata direttamente dalla redazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u2019ottima applicazione con un solo buco: non viene comunicato chi sia il talento tecnologico da ringraziare. In tutto il profluvio di stupore e meraviglia che Ferrara e Cerasa sciorinano nei loro commenti estasiati, si dimenticano di dirci &nbsp; chi \u00e8 il titolare del prodigio, di quale tipo di intelligenza artificiale si siano serviti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un dettaglio non da poco, la cui omissione potrebbe far scattare procedure di infrazione sia da parte dell\u2019Ordine dei Giornalisti &#8211; quando avr\u00e0 tempo di occuparsi di questo, che evidentemente a loro appare ancora come un <em>divertissement<\/em>, ad elezioni concluse &#8211; sia da parte della stessa magistratura, a norma della legge sulla stampa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infatti l\u2019intelligenza artificiale, a differenza di quanto mostrino di pensare i vertici del Foglio, non \u00e8 una tecnica uniforme e neutra, come potrebbe essere l\u2019energia elettrica, per cui basta dire: uso l\u2019intelligenza artificiale. Siamo oggi dinanzi ad un\u2019offerta varia e diversificata, dove ogni soluzione implica un risultato diverso, un modo di \u201cragionare\u201d, diciamo cos\u00ec, assolutamente differente. E\u2019 esattamente come dire leggo un giornale: quale? \u00c8 la domanda automatica. O ancora, per rimanere nell\u2019ambiente giornalistico, sarebbe come dire, me lo ha detto una fonte. Quale?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per questo \\\u00e8 indispensabile, in base al vincolo di trasparenza che deve legare ogni redazione ai suoi lettori, denunciare pubblicamente a quale fornitore ci si \u00e8 rivolti. Esattamente come si dichiara l\u2019identit\u00e0 delle fonti che si interpellano per un articolo. O che si citano dettagliatamente testi o relazioni. Che differenza c\u2019\u00e8? Noi sappiamo che Chat GPT, o Gemini di Google, o Claude di Anthropic, o ancora Gronk di Musk, sono modelli estremamente articolati e compositi in cui le reazioni agli input mutano radicalmente in base alla dieta di contenuti con cui \u00e8 stato alimentato il sistema e alle modalit\u00e0 di profilazione dell\u2019utente. Sono elementi questi che possono mutare sostanzialmente il risultato finale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diciamo che nel nuovo scenario in cui siamo immersi, dobbiamo adeguare le famose 5 W fondamentali del giornalismo: What? Where? Who? When?Why? riferendole esplicitamente alle protesi tecnologiche di cui ci si avvale. Senza questo corredo di informazioni siamo in un campo avventuroso dove ogni colpo di mano sarebbe possibile, tanto pi\u00f9 in un regime di guerra ibrida in cui si combatte, come spiegano i teorici delle nuove forme di cybersecurity, alterando il senso comune di un paese o di una comunit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questa logica, il direttore responsabile \u00e8 responsabile non solo per la trasparenza delle sue informazioni, per la libert\u00e0 della sua redazione ma anche per la sicurezza del suo paese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infatti adottando un sistema generativo importiamo vocabolari e set informativi da fonti che non conosciamo, introducendo nell\u2019infosfera nazionale un flusso di contenuti che dovremmo appunto certificare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si pone cosi, anche in vista del prossimo contratto nazionale dei giornalisti, che nello scenario di guerra ibrida non \u00e8 pi\u00f9 una questione sindacale di una categoria, ma riguarda l\u2019ordinamento di un settore strategico per la governabilit\u00e0 del paese, un\u2019altra questione su cui il duo Ferrara\/Cerasa ha allegramento soprasseduto. Infatti proprio perch\u00e9 siamo alle prese con un problema di sicurezza nazionale, \u00e8 quanto mai &nbsp; necessario, per un gruppo editoriale che decide di combinare capacit\u00e0 professionali con sistemi automatici, dare indicazioni esplicite sul modo con cui il sistema generativo che si \u00e8 utilizzato \u00e8 stato adattato&nbsp; nella specifica realt\u00e0 di quella specifica testata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nessun dispositivo di intelligenza artificiale pu\u00f2 continuativamente assicurare un flusso di elaborazioni quale quello ipotizzato da una macchina informativa che lavora 24 ore al giorno, quale \u00e8 oggi una testata giornalistica senza un lavoro di adattamento e di personalizzazione dei tools operativi. Dunque, questo lavoro che incide sull\u2019elaborazione del sistema, deve essere rappresentato. In concreto bisogna documentare il modo con cui il sistema \u00e8 stato addestrato, anzi meglio addomesticato.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spiegando quale processo di distillazione si \u00e8 allestito, ossia di addestramento basato su applicazioni maggiori da cui si ricavano meccanismi pi\u00f9 maneggevoli, con quali materiali e procedimenti di gestione nella macchina dei contenuti. Insomma, bisogna &#8211; qualora si decida di appaltare un prodotto giornalistico ad un meccanismo tecnologico, tale \u00e8 quanto ha fatto Il Foglio &#8211; avere la piena consapevolezza di come quel sistema opera, in base a quale&nbsp; processo di addestramento si \u00e8 formato&nbsp; il proprio senso comune, mediante il quale elabora i contenuti richiesti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La direzione della testata ci ha solo assicurato che sono stati i giornalisti a porre le domande. E questo \u00e8 davvero il minimo, vorrei anche vedere che cos\u00ec non fosse stato, avremmo avuto il primo caso di caporalato digitale, in cui un editore arruola un produttore, pi\u00f9 o meno retribuito, per svolgere un lavoro surrettiziamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma non basta l\u2019assicurazione che le domande siano state curate dalla redazione: bisogna che tutte le componenti della filiera giornale &#8211; dalla redazione, ai lettori -abbiano la piena padronanza del modo con cui quel sistema tecnologico \u00e8 stato organizzato e orientato in ognuna delle diverse fasi di addestramento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come dicevamo l\u2019intelligenza artificiale \u00e8 un apparato complesso che produce senso comune, logica ed etica della comunicazione. Possiamo bearci solo della sua perfezione operativa?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, questa \u00e8 proprio materia sindacale, la redazione dovrebbe dirci come \u00e8 stato concertato il progetto: il fornitore avr\u00e0 avuto un capitolato tecnico dalla direzione e dall\u2019editore, in base al quale ha messo a punto il prodotto. Come \u00e8 stato composto questo capitolato? chi ha parlato con il fornitore e i professionisti che hanno materialmente predisposto il sistema? La redazione \u00e8 stata soggetto anche nella fase di preparazione, cos\u00ec come la legge istitutiva dell\u2019ordine impone definendo il giornale sempre un\u2019opera collettiva?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insomma, Elon Musk direbbe che siamo alle solite ubbie burocratiche di chi vuole mettere le mutande al progresso. In realt\u00e0, bisogna spiegare a Musk, che qui in Europa, a differenza dal suo Sud Africa che gli diede i natali, e agli stati del sud americani, dove si trova a suo agio, le regole servono proprio per civilizzare il progresso . Ora dinanzi ad un salto del modo di fare giornalismo, si tratta non di esorcizzare il futuro, e nemmeno di ingabbiare l\u2019innovazione, ma anzi di accelerare l\u2019evoluzione tecnologica, allargando la schiera dei protagonisti, e mettendo pi\u00f9 capacit\u00e0 e esperienze al lavoro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019esperimento del Foglio potrebbe aiutarci in questo, individuando i buchi neri da illuminare e aumentando il livello di consapevolezza sia dei giornalisti che degli utenti che sempre pi\u00f9 sono co produttori della macchina giornale. Ma il nodo vero che dovremmo cominciare a considerare e che l\u2019intero sistema dell\u2019informazione, nei suoi processi evolutivi e di ibridazione socio tecnologica non \u00e8 pi\u00f9 un settore, per quanto importante ma collaterale, quanto invece uno dei cardini della governance e sicurezza di un paese, in un mondo che ha ormai sostituito la pace&nbsp; con una permanente guerra ibrida che rende la tecnologia di per s\u00e9 logistica militare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 19 marzo, San Giuseppe, mentre il governo faceva approvare al senato una legge denominata pomposamente regolamento per l\u2019intelligenza artificiale, Il Foglio, usciva con un supplemento completamento redatto da un sistema artificiale.<\/p>\n","protected":false},"author":6398,"featured_media":21711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-21710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec 19 marzo, San Giuseppe, mentre il governo faceva approvare al senato una legge denominata pomposamente regolamento per l\u2019intelligenza artificiale, Il Foglio, usciva con un supplemento completamento redatto da un sistema artificiale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-24T09:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T17:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michele Mezza**\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Mezza**\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/\"},\"author\":{\"name\":\"Michele Mezza**\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/78b2570c7d80c9fbaedf56c8adf33118\"},\"headline\":\"What? Where? Who? When? Why? al tempo della IA\",\"datePublished\":\"2025-03-24T09:35:31+00:00\",\"dateModified\":\"2025-03-25T17:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/\"},\"wordCount\":1444,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/howwhat.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/\",\"name\":\"What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/howwhat.jpg\",\"datePublished\":\"2025-03-24T09:35:31+00:00\",\"dateModified\":\"2025-03-25T17:05:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/howwhat.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/howwhat.jpg\",\"width\":1400,\"height\":1294},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/what-where-who-when-why-al-tempo-della-ia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"What? Where? Who? When? Why? al tempo della IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/78b2570c7d80c9fbaedf56c8adf33118\",\"name\":\"Michele Mezza**\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g\",\"caption\":\"Michele Mezza**\"},\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/michele-mezza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/","og_locale":"it_IT","og_type":"article","og_title":"What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori","og_description":"Mercoled\u00ec 19 marzo, San Giuseppe, mentre il governo faceva approvare al senato una legge denominata pomposamente regolamento per l\u2019intelligenza artificiale, Il Foglio, usciva con un supplemento completamento redatto da un sistema artificiale.","og_url":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/","og_site_name":"Nuovi Lavori","article_published_time":"2025-03-24T09:35:31+00:00","article_modified_time":"2025-03-25T17:05:46+00:00","og_image":[{"width":1400,"height":1294,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg","type":"image\/jpeg"}],"author":"Michele Mezza**","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michele Mezza**","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/"},"author":{"name":"Michele Mezza**","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/78b2570c7d80c9fbaedf56c8adf33118"},"headline":"What? Where? Who? When? Why? al tempo della IA","datePublished":"2025-03-24T09:35:31+00:00","dateModified":"2025-03-25T17:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/"},"wordCount":1444,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/","url":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/","name":"What? Where? Who? When? Why? al tempo della IA - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg","datePublished":"2025-03-24T09:35:31+00:00","dateModified":"2025-03-25T17:05:46+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/howwhat.jpg","width":1400,"height":1294},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/what-where-who-when-why-al-tempo-della-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"What? Where? Who? When? Why? al tempo della IA"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/78b2570c7d80c9fbaedf56c8adf33118","name":"Michele Mezza**","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52a9cc0c28ef47164ff66b6622fa5e4e65b1ff5a45fae841c98bffcee393abc2?s=96&d=mm&r=g","caption":"Michele Mezza**"},"url":"https:\/\/nuovi-lavori.it\/index.php\/author\/michele-mezza\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6398"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=21710"}],"version-history":[{"count":1,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21710\/revisions"}],"predecessor-version":[{"id":21712,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21710\/revisions\/21712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/21711"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=21710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=21710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=21710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}