{"id":21713,"date":"2025-03-25T15:36:35","date_gmt":"2025-03-25T14:36:35","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=21713"},"modified":"2025-03-25T18:42:29","modified_gmt":"2025-03-25T17:42:29","slug":"cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/","title":{"rendered":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In venti anni, si sono iscritti alla scuola quasi un milione di ragazzi e ragazze in meno. A settembre dello scorso anno, il dimagrimento \u00e8 stato di 134.000 circa. Per l\u2019anno scolastico prossimo ci potrebbero essere 5.667 cattedre di troppo. E le previsioni sono che il trend in discesa continui sempre di pi\u00f9. Lo dice il Ministero dell\u2019istruzione e del Merito, come pomposamente lo ha denominato il Ministro Valditara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La denatalit\u00e0 picchia duro sulla demografia nazionale. E poco conta che sia un mal comune con la maggior parte dei Paesi europei, anche se peggio di noi stanno soltanto Portogallo e Spagna. Soltanto 4 Paesi registrano un aumento delle nascite: Irlanda, Francia, Regno Unito e Svezia. Gli altri 23 tutti con il segno negativo. Aggrava la situazione il fatto che si \u00e8 passati dal fare soltanto un figlio &#8211; per cui non pu\u00f2 pi\u00f9 essere esercitata l\u2019esperienza della fraternit\u00e0 in famiglia e diventati adulti si estingue la figura dello zio o della zia &#8211; a non farne proprio. Infatti, dal 2008 ad oggi i primogeniti sono diminuiti del 34,4%, i secondogeniti del 36,3% e i successivi del 26,5%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fronte di questo scenario pauperistico, le belle parole si sprecano, ma passano come acqua fresca sulle coppie pi\u00f9 o meno giovani che in questi ultimi trent\u2019anni, non hanno smesso di far calare con regolarit\u00e0 l\u2019indice di natalit\u00e0. E\u2019 un errore incolpare i protagonisti e in pi\u00f9 sarebbe predica inutile. Questa discesa ha camminato di pari passo con un andazzo politico distonico, parlando bene (raramente) e razzolando male (frequentemente). Una strategia per l\u2019inversione della tendenza, non \u00e8 stata mai impostata correttamente e decisamente. Ci sono stati provvedimenti anche significativi (aumento dei congedi parentali, pi\u00f9 asili nido, ecc.) ma senza una correlazione con altri interventi, pur individuati anche se non risolutivi, spesso ridotti a pura testimonianza per carenza di strutture e di finanziamenti adeguati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eppure le conseguenze sono prevedibili. Innanzitutto, sul futuro del sistema produttivo italiano. Un Paese che invecchia sempre pi\u00f9 rapidamente, non \u00e8 attrattivo per gli investimenti. E\u2019 ormai un dato acclarato da molte indagini. Gli investitori si rivolgono a Paesi che danno pi\u00f9 garanzie di potenzialit\u00e0 di lavoratori giovani. Lo abbiamo sperimentato in questi due anni di buona congiuntura. L\u2019occupazione stabile \u00e8 cresciuta soprattutto nelle fasce d\u2019et\u00e0 pi\u00f9 anziane, sia per mancanza di professionalit\u00e0 formate dal sistema scolastico e universitario corrispondenti alle esigenze delle produzioni in corso, sia per assenza di disponibilit\u00e0 di giovani da assumere, comunque. In tempi in cui c\u2019\u00e8 una forte innovazione di prodotti e di tecnologie si rischia di rimanere fuori mercato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In secondo luogo, sulle prospettive di sostenibilit\u00e0 del welfare. Chi ha pi\u00f9 bisogno di sanit\u00e0 funzionante, di assistenza decente, di vivibilit\u00e0 delle citt\u00e0 sono le fasce pi\u00f9 vecchie della popolazione. Ma se si restringe l\u2019area dei finanziatori dell\u2019intervento pubblico, per contrazione dei contribuenti tradizionali (il welfare \u00e8 sostenuto dai redditi da lavoro e dai pensionati, oltre che dal debito pubblico), \u00e8 evidente che lo Stato sociale pu\u00f2 diventare un ricordo del passato. Gi\u00e0 ora la situazione \u00e8 pesante, con preoccupanti scivolate verso un ridimensionamento del concetto di universalit\u00e0 nella sua fruizione. Pi\u00f9 difficile sar\u00e0 in futuro cercare di dare un nuovo equilibrio al welfare, se non si interviene ora per allora, con grande consapevolezza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le soluzioni sono terribilmente difficili. Ma la politica dei rinvii \u00e8 il peggior modo per rassicurare. Innanzitutto, c\u2019\u00e8 un problema di reddito delle famiglie, adeguato agli stili di vita mediamente affermati. Non si pu\u00f2 pensare che si facciano figli per cadere in una situazione di povert\u00e0. Il sistema fiscale italiano non si attiene a questa banale osservazione e gli assegni familiari sono troppo miseri per essere compensativi delle spese di una famiglia che si collochi nella media europea. A fianco ad una revisione dei sostegni fiscali, anche la contrattazione nazionale e quella aziendale potrebbero mettere pi\u00f9 attenzione al fenomeno della denatalit\u00e0. Ricordo che uno dei motivi del successo di Blair alle sue prime elezioni inglesi fu la proposta di contribuire con una somma da parte dello Stato pari a quella accantonata dalle famiglie per gli studi dei figli. Nella contrattazione del welfare aziendale potrebbe entrare un concetto di questo genere, come potrebbe essere rilanciato il \u201csabbatico\u201d come possibilit\u00e0 di avere lunghi periodi di assenza dal lavoro, remunerati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019\u00e8 inoltre, un problema di servizi offerti alle famiglie. Non ripeto la solita litania degli interventi pubblici per alleviare il peso della gestione familiare. Sono tutti stranoti e sarebbero tutti necessari. Ma risulterebbero pi\u00f9 facilitati e moltiplicati se si facesse perno anche sul volontariato degli anziani. Ci sono ormai molte esperienze collaudate nel territorio, finalizzate a dare una mano nella collaborazione con le famiglie, che potrebbero essere portate a sistema e diffuse, oltre che sostenute con poche ma ben utilizzate risorse pubbliche. Una maggior cooperazione privato-pubblica potrebbe rappresentare un incentivo a guardare al futuro con maggiore serenit\u00e0 da parte delle giovani coppie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per\u00f2, nel breve periodo soltanto l\u2019immigrazione pu\u00f2 consentirci di colmare i vuoti generazionali e affrontare con minore affanno le questioni prima accennate. Se ne facciano una ragione i cantori dei respingimenti. Ne abbiamo bisogno, se vogliamo tenere il passo con i tempi. Non \u00e8 solo colpa loro se creano disordine, se squilibrano quartieri e costumi. Siamo noi che non organizziamo l\u2019accoglienza e l\u2019inserimento come esigenza strutturale nelle nostre comunit\u00e0. Si pu\u00f2 chiedere di adeguarsi di pi\u00f9 e meglio alle nostre abitudini e comportamenti se li mettiamo in condizioni di poterlo fare. Conoscere le nostre regole di vita e la nostra lingua \u00e8 pretesa sacrosanta ma dobbiamo organizzarla con razionalit\u00e0. Si sprecano miliardi per deportare piccoli gruppi di migranti in Albania e si tagliano i finanziamenti per l&#8217;insegnamento dell\u2019italiano. Si riempiono le carceri di disperati, ma non si fa niente per eliminare il lavoro nero e sottopagato di questi poveracci. Tutte le ricerche dicono la stessa cosa: sono necessari per creare ricchezza. Prendiamone atto e mettiamo in campo un sistema pi\u00f9 ordinato e programmato di arrivi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, cerchiamo di salvare la scuola. Non solo dagli abbandoni, dalla dispersione scolastica ma dal rischio di non essere pi\u00f9 in buona salute in fatto di educazione. Commentando in una bella intervista su la Lettura del 23 marzo scorso il suo libro \u201cConoscenza o barbarie, Storia e futuro dell\u2019educazione, ed. Fazi\u201d conclude: \u201csiamo ad un bivio. Dovremmo triplicare gli investimenti e insistere con l\u2019idea delle quote per riservare posti nelle migliori scuole ad allievi che arrivano dalle periferie. La riproduzione sociale \u00e8 uno scandalo: in Francia il figlio di uno studente di una universit\u00e0 d\u2019\u00e9lite ha 80 volte pi\u00f9 probabilit\u00e0 di frequentare la stessa universit\u00e0 di \u00e9lite rispetto ad un altro. Siamo ancora in tempo per salvarci\u2026.la particolarit\u00e0 della partita \u00e8 che siamo nell\u2019intervallo dopo il primo tempo, stiamo perdendo 3 a 0 e l\u2019avversario siamo noi stessi\u201d. Per\u00f2 non possiamo fare come l\u2019Italia contro la Germania, che rimonta ma non vince.&nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In venti anni, si sono iscritti alla scuola quasi un milione di ragazzi e ragazze in meno. A settembre dello scorso anno, il dimagrimento \u00e8 stato di 134.000 circa. <\/p>\n","protected":false},"author":6341,"featured_media":21714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-21713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"In venti anni, si sono iscritti alla scuola quasi un milione di ragazzi e ragazze in meno. A settembre dello scorso anno, il dimagrimento \u00e8 stato di 134.000 circa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T14:36:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T17:42:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"839\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raffaele Morese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raffaele Morese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/\"},\"author\":{\"name\":\"Raffaele Morese\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/4768859afb8ce507df626060d213b701\"},\"headline\":\"Cifre preoccupanti. Una scuola specchio di questioni irrisolte\",\"datePublished\":\"2025-03-25T14:36:35+00:00\",\"dateModified\":\"2025-03-25T17:42:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/\"},\"wordCount\":1142,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/\",\"name\":\"Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg\",\"datePublished\":\"2025-03-25T14:36:35+00:00\",\"dateModified\":\"2025-03-25T17:42:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg\",\"width\":1260,\"height\":839},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cifre preoccupanti. Una scuola specchio di questioni irrisolte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/4768859afb8ce507df626060d213b701\",\"name\":\"Raffaele Morese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g\",\"caption\":\"Raffaele Morese\"},\"description\":\"Laureato in economia e commercio all'Universit\u00e0 Cattolica di Milano. Nel 1966 \u00e8 responsabile dell'Ufficio Studi e Marketing della Rinascente S.p.A., nel 1967 entra all\u2019Ufficio Studi della CISL. Nel 1969 avvia la sua attivit\u00e0 sindacale come operatore nella Fim-Cisl nazionale, di cui diviene segretario nazionale nel 1975, ricoprendo la responsabilit\u00e0 di vari settori (elettromeccanica, informatica, siderurgia, e infine auto e trasporti) e assumendo il coordinamento delle politiche sindacali. Nel 1983 succede a Franco Bentivogli come segretario generale della Fim-Cisl e nel 1989 passa alla segreteria nazionale della confederazione, di cui diviene segretario generale aggiunto, in coppia con Sergio D'Antoni segretario generale. Nel 1998 si conclude la sua esperienza sindacale e si apre una fase di impegno politico nelle file del centro-sinistra. Dal 1998 al 2001 \u00e8 Sottosegretario con delega al Ministero del Lavoro. Dal 2002 al 2009 \u00e8 stato presidente di Trambus, la societ\u00e0 per azioni del Comune di Roma che gestisce la maggior parte del trasporto pubblico di Roma. Dal 2004 al 2009 \u00e8 stato presidente di Confservizi, la confederazione nazionale che rappresenta le aziende e gli enti che gestiscono i Servizi Pubblici Locali. Morese \u00e8 stato inoltre Consigliere del Consiglio Nazionale dell'Economia e del Lavoro (CNEL) nella IV Consiliatura, e nel 2005 \u00e8 stato nominato presidente della Commissione per le grandi opere e le reti infrastrutturali, per le politiche energetiche e i servizi di rete. Dal 1996 al 2009 \u00e8 stato Presidente di Intersos, la pi\u00f9 grande ONG italiana per l\u2019intervento umanitario nelle situazioni di guerra, di calamit\u00e0 naturali, di epidemie. Ha inoltre collaborato con numerosi quotidiani e settimanali, quali Sette giorni, Mondo Operaio, Il Popolo, Il Nuovo e L\u2019Europa, ed \u00e8 autore di diverse pubblicazioni sul mondo del lavoro, come Lavorare meno, lavorare tutti, Le Frontiere della partecipazione, Contare fino a uno e Ridistribuire il lavoro. Attualmente \u00e8 Segretario Generale di \\\"Nuovi Lavori\\\" (NL) e Presidente del think tank Koin\u00e8.\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/raffaele-morese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/","og_locale":"it_IT","og_type":"article","og_title":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori","og_description":"In venti anni, si sono iscritti alla scuola quasi un milione di ragazzi e ragazze in meno. A settembre dello scorso anno, il dimagrimento \u00e8 stato di 134.000 circa.","og_url":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/","og_site_name":"Nuovi Lavori","article_published_time":"2025-03-25T14:36:35+00:00","article_modified_time":"2025-03-25T17:42:29+00:00","og_image":[{"width":1260,"height":839,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg","type":"image\/jpeg"}],"author":"Raffaele Morese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Raffaele Morese","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/"},"author":{"name":"Raffaele Morese","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/4768859afb8ce507df626060d213b701"},"headline":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte","datePublished":"2025-03-25T14:36:35+00:00","dateModified":"2025-03-25T17:42:29+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/"},"wordCount":1142,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/","url":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/","name":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg","datePublished":"2025-03-25T14:36:35+00:00","dateModified":"2025-03-25T17:42:29+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2025\/03\/Scuola-meno-nati-banchi-vuoti_articleimage.jpg","width":1260,"height":839},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/cifre-preoccupanti-una-scuola-vittima-di-questioni-piu-grandi-di-lie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Cifre preoccupanti. Una scuola specchio di questioni irrisolte"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/4768859afb8ce507df626060d213b701","name":"Raffaele Morese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9e93dd33a56fe3d005bd3f6c40cb88951704b941daa4f4dd789da460905d0d7?s=96&d=mm&r=g","caption":"Raffaele Morese"},"description":"Laureato in economia e commercio all'Universit\u00e0 Cattolica di Milano. Nel 1966 \u00e8 responsabile dell'Ufficio Studi e Marketing della Rinascente S.p.A., nel 1967 entra all\u2019Ufficio Studi della CISL. Nel 1969 avvia la sua attivit\u00e0 sindacale come operatore nella Fim-Cisl nazionale, di cui diviene segretario nazionale nel 1975, ricoprendo la responsabilit\u00e0 di vari settori (elettromeccanica, informatica, siderurgia, e infine auto e trasporti) e assumendo il coordinamento delle politiche sindacali. Nel 1983 succede a Franco Bentivogli come segretario generale della Fim-Cisl e nel 1989 passa alla segreteria nazionale della confederazione, di cui diviene segretario generale aggiunto, in coppia con Sergio D'Antoni segretario generale. Nel 1998 si conclude la sua esperienza sindacale e si apre una fase di impegno politico nelle file del centro-sinistra. Dal 1998 al 2001 \u00e8 Sottosegretario con delega al Ministero del Lavoro. Dal 2002 al 2009 \u00e8 stato presidente di Trambus, la societ\u00e0 per azioni del Comune di Roma che gestisce la maggior parte del trasporto pubblico di Roma. Dal 2004 al 2009 \u00e8 stato presidente di Confservizi, la confederazione nazionale che rappresenta le aziende e gli enti che gestiscono i Servizi Pubblici Locali. Morese \u00e8 stato inoltre Consigliere del Consiglio Nazionale dell'Economia e del Lavoro (CNEL) nella IV Consiliatura, e nel 2005 \u00e8 stato nominato presidente della Commissione per le grandi opere e le reti infrastrutturali, per le politiche energetiche e i servizi di rete. Dal 1996 al 2009 \u00e8 stato Presidente di Intersos, la pi\u00f9 grande ONG italiana per l\u2019intervento umanitario nelle situazioni di guerra, di calamit\u00e0 naturali, di epidemie. Ha inoltre collaborato con numerosi quotidiani e settimanali, quali Sette giorni, Mondo Operaio, Il Popolo, Il Nuovo e L\u2019Europa, ed \u00e8 autore di diverse pubblicazioni sul mondo del lavoro, come Lavorare meno, lavorare tutti, Le Frontiere della partecipazione, Contare fino a uno e Ridistribuire il lavoro. Attualmente \u00e8 Segretario Generale di \"Nuovi Lavori\" (NL) e Presidente del think tank Koin\u00e8.","url":"https:\/\/nuovi-lavori.it\/index.php\/author\/raffaele-morese\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6341"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=21713"}],"version-history":[{"count":3,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21713\/revisions"}],"predecessor-version":[{"id":21731,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/21713\/revisions\/21731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/21714"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=21713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=21713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=21713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}