{"id":23098,"date":"2026-05-11T22:03:00","date_gmt":"2026-05-11T20:03:00","guid":{"rendered":"https:\/\/nuovi-lavori.it\/?p=23098"},"modified":"2026-05-13T17:02:12","modified_gmt":"2026-05-13T15:02:12","slug":"palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza","status":"publish","type":"post","link":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/","title":{"rendered":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza"},"content":{"rendered":"\n<p><em>Il 18 aprile Palantir, fornitore di piattaforme di analisi dati per eserciti e intelligence in mezzo mondo, ha pubblicato un documento in 22 punti \u2013 32 milioni di visualizzazioni \u2013 letto da molti come un manifesto politico. Ne parliamo con Michele Mezza: per il giornalista e studioso degli algoritmi, \u00e8 \u00abuna nuova scena antropologica\u00bb.Michele Mezza \u00e8 anche docente universitario e autore di numerosi saggi. Ll\u2019ultimo, appena uscito, si intitola: <\/em><strong><em>Guerre in Codice,come le intelligenze artificiali resettano la democrazia (Donzelli editore).<\/em><\/strong><\/p>\n\n\n\n<p><strong>Professor Mezza, il 18 aprile Palantir \u2013 una societ\u00e0 che fornisce piattaforme di analisi dati a eserciti, intelligence e forze di polizia in mezzo mondo \u2013 ha pubblicato sui propri canali un documento in 22 punti che molti commentatori hanno letto come un vero e proprio manifesto politico. Quanto \u00e8 inedito, nella storia recente, che un&#8217;azienda di questo profilo prenda cos\u00ec esplicitamente posizione su cultura, valori e modello di societ\u00e0?<\/strong><\/p>\n\n\n\n<p>In realt\u00e0 non \u00e8 inedito affatto. Nel secolo scorso le imprese che davano forma al cosiddetto fordismo, cio\u00e8 ad un modo di organizzare non solo la produzione seriale ma la stessa societ\u00e0, omologando comportamenti e relazioni, gi\u00e0 elaboravano strategie e precetti per omologare i tratti salienti della societ\u00e0 di massa. Negli Usa a fine \u2019800 prese forma un movimento, il cosiddetto partito degli ingegneri, che mirava proprio a sostituire le istituzioni democratiche con le tecnocrazie di comando ricavate dai quadri dirigenti delle aziende manageriali. In Italia, su un versante opposto, non possiamo non ricordare il fenomeno olivettiano, quando negli anni \u201950 il paternalismo tipico delle grandi famiglie industriali del Nord venne declinato in una versione pi\u00f9 illuminata e partecipativa con il movimento Comunit\u00e0 di Adriano Olivetti. Quello che appare del tutto sorprendente dell\u2019interventismo dei vertici di Palantir \u00e8 la cruda sincerit\u00e0 con cui avanzano proposte radicali che mirano a sostituire la democrazia con la tecnologia predittiva. Qui cambia la storia e si apre una nuova scena antropologica.<\/p>\n\n\n\n<p><strong>Uno dei passaggi pi\u00f9 discussi sostiene che la capacit\u00e0 delle democrazie di prevalere richieda non pi\u00f9 soft power e retorica, ma \u00abhard power\u00bb, e che questo hard power, nel nostro secolo, si costruir\u00e0 sul software. Lei studia da anni il rapporto fra algoritmo e potere: che cosa cambia, per la sovranit\u00e0 democratica, quando la forza di uno Stato viene fatta coincidere con il codice prodotto da poche aziende private?&nbsp;<\/strong><\/p>\n\n\n\n<p>Cambia l\u2019idea stessa di Stato. Noi sappiamo che l\u2019istituzione dello Stato nazionale nasce proprio con il diffondersi della stampa, che d\u00e0 forma e linguaggio all\u2019opinione pubblica e fornisce una base materiale al carisma dell\u2019autorit\u00e0 statuale. Con quel carisma Carl Schmitt, il grande filosofo del potere centralizzato, arriv\u00f2 a legare la legittimit\u00e0 dello Stato alla sua capacit\u00e0 di proclamare lo stato di emergenza, sospendendo le prerogative democratiche e imponendo una mediazione e limitazione dei poteri privati. Oggi Peter Thiel e Alexander Karp sostengono che le tecnologie psico-sociali, quali sono quelle basate sulla profilazione di ogni individuo, devono sostituire e non supportare lo Stato, eliminando ogni impedimento pubblico ai poteri privati dei proprietari di queste tecnologie. In discussione non c\u2019\u00e8 il dominio di un monopolio ma la sostituzione di ogni istituzione pubblica con un sistema proprietario.<\/p>\n\n\n\n<p><strong>Il manifesto contiene anche giudizi netti \u2013 alcune culture sarebbero \u00abdisfunzionali e regressive\u00bb, il pluralismo sarebbe diventato \u00abvuoto e vacuo\u00bb. Qui non parla un think tank, ma chi fornisce gli strumenti con cui si decide quali soggetti sorvegliare, quali profili segnalare, quali aree presidiare. Quanto \u00e8 problematico, dal suo punto di vista, che chi costruisce l&#8217;infrastruttura della sicurezza si proponga anche come arbitro del giudizio culturale?<\/strong><\/p>\n\n\n\n<p>Non solo arbitro ma anche tutore di ogni utente. Non dimentichiamo che lo strapotere della Silicon Valley si basa sul controllo pressoch\u00e9 esclusivo della profilazione di ognuno dei circa 5 miliardi di utenti della rete. Sono i dati intimi di ogni individuo che hanno animato le intelligenze artificiali accelerando la corsa alla virtualizzazione dell\u2019umanit\u00e0. Dall\u2019alto di questo potere al momento non contestato n\u00e9 socialmente n\u00e9 politicamente ci si spinge fino a pretendere uno stravolgimento culturale dell\u2019intero Occidente, usando come pretesto la stagnazione tecnologica che i dirigenti di Palantir legano all\u2019effetto paralizzante del pluralismo. Il nemico da rimuovere, lo spiega benissimo Peter Thiel nel suo saggio del 2004 <em>Il Momento Straussiano<\/em>, \u00e8 l\u2019Illuminismo, l\u2019avvento della ragione come centro delle relazioni umane, e per sferrare quest\u2019attacco si usa anche la religione nella sua versione pi\u00f9 tenebrosa in cui si parla di Anticristo.<\/p>\n\n\n\n<p><strong>Palantir non \u00e8 un fenomeno solo americano: i suoi sistemi sono integrati in apparati militari, sanitari e di sicurezza in vari Paesi europei, Italia compresa. C&#8217;\u00e8 un tema di consapevolezza pubblica che sembra mancare. Si discute di sovranit\u00e0 digitale soprattutto in chiave anti-cinese, ma l&#8217;Europa ha davvero gli strumenti \u2013 politici, giuridici, industriali \u2013 per leggere e governare questo tipo di dipendenza?<\/strong><\/p>\n\n\n\n<p>L\u2019Europa ha fatto un grande lavoro dal punto di vista legislativo, con norme, pensiamo ad esempio al GDPR per regolare la gestione dei dati, che sono obiettivamente all\u2019avanguardia. Ma la domanda da porsi \u00e8 se un fenomeno cos\u00ec fluido e mutevole quale la metamorfosi tecnologica sia disciplinabile e limitabile con un sistema legislativo lento e farraginoso, o piuttosto non sia indispensabile attivare forme di controllo e negoziazione sociale, mediante piattaforme pubbliche di monitoraggio e misurazione degli algoritmi che possano intervenire in tempo reale. Innescare processi negoziali darebbe corso e forza anche ad una democrazia attiva e contemporanea in grado di parlare alle generazioni digitali.<\/p>\n\n\n\n<p><strong>Il manifesto rivendica un ruolo della Silicon Valley nella difesa nazionale e perfino nel contrasto al crimine violento, accusando la classe politica di aver \u00abalzato le spalle\u00bb. \u00c8 una cornice che, paradossalmente, presenta l&#8217;azienda tecnologica come supplenza necessaria alla politica democratica. Non c&#8217;\u00e8 qui, dietro il linguaggio dell&#8217;efficienza, un rovesciamento del rapporto fra potere pubblico e potere privato che meriterebbe almeno qualche segnale di inquietudine?<\/strong><\/p>\n\n\n\n<p>Lo dicevamo prima. La filosofia di Palantir \u00e8 che la tecnologia governa e decide e la politica comunica. Una visione chiaramente autoritaria che assume l\u2019automatismo matematico come filosofia sociale, come infrastruttura relazionale. Contrastare questa visione significa non denunciare la tecnologia tout court come minaccia ma l\u2019inverso. Civilizzare un sistema che assicura, se correttamente applicato, l\u2019emancipazione di grandi moltitudini di individui che devono essere protagonisti e non sudditi di questi automatismi.<\/p>\n\n\n\n<p><strong>Lei viene da una lunga esperienza giornalistica e ha contribuito a costruire RaiNews24. Di fronte a un documento di questa portata \u2013 e ai 32 milioni di visualizzazioni che ha raccolto \u2013 il giornalismo italiano e il mondo accademico stanno facendo abbastanza per spiegare al pubblico la posta in gioco? E quali, secondo lei, dovrebbero essere oggi i contrappesi minimi \u2013 informativi, regolatori, culturali \u2013 perch\u00e9 il dibattito sull&#8217;IA non venga lasciato del tutto a chi ne controlla l&#8217;infrastruttura?<\/strong><\/p>\n\n\n\n<p>I giornalisti non devono predicare ma agire ed essere soggetti del processo di civilizzazione degli algoritmi mediante un\u2019azione consapevole di intervento e riprogrammazione delle macchine. Proprio i giornalisti, come titolari di un uso professionale delle parole, del capitale semantico fondamentale per addestrare e personalizzare questi apparati, dovrebbero essere tra i soggetti negoziali dei proprietari delle piattaforme, insieme ad altre professioni, penso ai medici ad esempio. E con loro le grandi citt\u00e0 possono essere controparti di un uso consapevole e trasparente dei dispositivi di intelligenza artificiale. Promuovere un\u2019ampia contrattazione sociale che sfrutti la tendenza naturale al decentramento dell\u2019informatica per maneggiare questi sistemi digitali \u00e8 forse l\u2019unica opportunit\u00e0 che abbiamo per rendere umanamente compatibile la potenza di calcolo con la democrazia.<\/p>\n\n\n\n<p>Dal sito: www.raines.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 18 aprile Palantir, fornitore di piattaforme di analisi dati per eserciti e intelligence in mezzo mondo, ha pubblicato un documento in 22 punti &#8230;.<\/p>\n","protected":false},"author":6358,"featured_media":23147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-23098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori\" \/>\n<meta property=\"og:description\" content=\"Il 18 aprile Palantir, fornitore di piattaforme di analisi dati per eserciti e intelligence in mezzo mondo, ha pubblicato un documento in 22 punti ....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuovi Lavori\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T20:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T15:02:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierluigi Mele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierluigi Mele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/\"},\"author\":{\"name\":\"Pierluigi Mele\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/9eaf2b92e5244284c7b802d840acab22\"},\"headline\":\"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza\",\"datePublished\":\"2026-05-11T20:03:00+00:00\",\"dateModified\":\"2026-05-13T15:02:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/\"},\"wordCount\":1232,\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/palantiroooo.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/\",\"name\":\"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/palantiroooo.jpg\",\"datePublished\":\"2026-05-11T20:03:00+00:00\",\"dateModified\":\"2026-05-13T15:02:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/palantiroooo.jpg\",\"contentUrl\":\"https:\\\/\\\/nuovi-lavori.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/palantiroooo.jpg\",\"width\":1000,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\",\"item\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/category\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#website\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"name\":\"Nuovi Lavori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuovi-lavori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#organization\",\"name\":\"Nuovi Lavori\",\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"contentUrl\":\"http:\\\/\\\/5.249.146.118\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/images_logonl.jpg\",\"width\":400,\"height\":327,\"caption\":\"Nuovi Lavori\"},\"image\":{\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/newsletteranl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuovi-lavori.it\\\/#\\\/schema\\\/person\\\/9eaf2b92e5244284c7b802d840acab22\",\"name\":\"Pierluigi Mele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g\",\"caption\":\"Pierluigi Mele\"},\"url\":\"https:\\\/\\\/nuovi-lavori.it\\\/index.php\\\/author\\\/pierluigi-mele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/","og_locale":"it_IT","og_type":"article","og_title":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori","og_description":"Il 18 aprile Palantir, fornitore di piattaforme di analisi dati per eserciti e intelligence in mezzo mondo, ha pubblicato un documento in 22 punti ....","og_url":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/","og_site_name":"Nuovi Lavori","article_published_time":"2026-05-11T20:03:00+00:00","article_modified_time":"2026-05-13T15:02:12+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg","type":"image\/jpeg"}],"author":"Pierluigi Mele","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Pierluigi Mele","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#article","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/"},"author":{"name":"Pierluigi Mele","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/9eaf2b92e5244284c7b802d840acab22"},"headline":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza","datePublished":"2026-05-11T20:03:00+00:00","dateModified":"2026-05-13T15:02:12+00:00","mainEntityOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/"},"wordCount":1232,"publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/","url":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/","name":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza - Nuovi Lavori","isPartOf":{"@id":"https:\/\/nuovi-lavori.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#primaryimage"},"image":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#primaryimage"},"thumbnailUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg","datePublished":"2026-05-11T20:03:00+00:00","dateModified":"2026-05-13T15:02:12+00:00","breadcrumb":{"@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#primaryimage","url":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg","contentUrl":"https:\/\/nuovi-lavori.it\/wp-content\/uploads\/2026\/05\/palantiroooo.jpg","width":1000,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/nuovi-lavori.it\/index.php\/palantir-manifesto-in-22-punti-contro-la-democrazia-parla-michele-mezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuovi-lavori.it\/"},{"@type":"ListItem","position":2,"name":"Newsletter","item":"https:\/\/nuovi-lavori.it\/index.php\/category\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Palantir, manifesto in 22 punti contro la democrazia: parla Michele Mezza"}]},{"@type":"WebSite","@id":"https:\/\/nuovi-lavori.it\/#website","url":"https:\/\/nuovi-lavori.it\/","name":"Nuovi Lavori","description":"","publisher":{"@id":"https:\/\/nuovi-lavori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuovi-lavori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuovi-lavori.it\/#organization","name":"Nuovi Lavori","url":"https:\/\/nuovi-lavori.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/","url":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","contentUrl":"http:\/\/5.249.146.118\/wp-content\/uploads\/2013\/11\/images_logonl.jpg","width":400,"height":327,"caption":"Nuovi Lavori"},"image":{"@id":"https:\/\/nuovi-lavori.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/newsletteranl"]},{"@type":"Person","@id":"https:\/\/nuovi-lavori.it\/#\/schema\/person\/9eaf2b92e5244284c7b802d840acab22","name":"Pierluigi Mele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d33d7099b67075c1f4465a6f9c2bf3bc484b6c9640b1b30d007517928393ab01?s=96&d=mm&r=g","caption":"Pierluigi Mele"},"url":"https:\/\/nuovi-lavori.it\/index.php\/author\/pierluigi-mele\/"}]}},"_links":{"self":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/23098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/users\/6358"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/comments?post=23098"}],"version-history":[{"count":3,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/23098\/revisions"}],"predecessor-version":[{"id":23148,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/posts\/23098\/revisions\/23148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media\/23147"}],"wp:attachment":[{"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/media?parent=23098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/categories?post=23098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovi-lavori.it\/index.php\/wp-json\/wp\/v2\/tags?post=23098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}